{"id":8463,"date":"2024-02-16T09:36:55","date_gmt":"2024-02-16T14:36:55","guid":{"rendered":"https:\/\/www-dev.absglobal.com\/br\/?post_type=abs_news_article&#038;p=8463"},"modified":"2024-02-16T09:36:56","modified_gmt":"2024-02-16T14:36:56","slug":"1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva","status":"publish","type":"abs_news_article","link":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/","title":{"rendered":"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva"},"content":{"rendered":"\n<p><em>A\u00e7\u00e3o on-line vai ofertar s\u00eamen convencional e s\u00eamen sexado de touros de elevado valor gen\u00e9tico; live ser\u00e1 transmitida no Instagram da ABS, na pr\u00f3xima ter\u00e7a-feira (20), \u00e0s 19h<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" height=\"850\" width=\"1024\" src=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?w=1024\" alt=\"\" class=\"wp-image-8464\" srcset=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg 4626w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?resize=300,249 300w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?resize=768,638 768w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?resize=1024,850 1024w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?resize=1536,1275 1536w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?resize=2048,1700 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A busca constante por mais produtividade e rendimento exige que os produtores invistam cada vez mais em gen\u00e9tica de qualidade. Com uma bateria de touros l\u00edder de mercado e tecnologia de ponta, a ABS realizar\u00e1, na pr\u00f3xima ter\u00e7a-feira (20), \u00e0s 19h, a 1\u00aa Live Shop voltada para as ra\u00e7as Guzer\u00e1 e Sindi com aptid\u00e3o leiteira.<\/p>\n\n\n\n<p>Com os avan\u00e7os tecnol\u00f3gicos, o ambiente virtual passou a fazer parte tamb\u00e9m da vida do produtor. E a 1\u00aa Live Shop dar\u00e1 oportunidade para que pecuaristas de leite adquiram gen\u00e9tica de forma f\u00e1cil e r\u00e1pida para potencializar a produ\u00e7\u00e3o de leite nas propriedades em todo o pa\u00eds.<\/p>\n\n\n\n<p>A live ter\u00e1 participa\u00e7\u00e3o do Coordenador de Produto e Atendimento ao Cliente Leite da ABS, Fernando Rosa, al\u00e9m dos pecuaristas Marcelo Lack (Guzer\u00e1 Boa Lembran\u00e7a), e Joaquim Dantas (Fazenda Carna\u00faba), refer\u00eancias na sele\u00e7\u00e3o das referidas ra\u00e7as. \u201cSer\u00e1 uma oportunidade para debater os principais assuntos pertinentes \u00e0 produ\u00e7\u00e3o leiteira no Brasil e, especificamente, no que se refere ao melhoramento das ra\u00e7as Guzer\u00e1 e Sindi\u201d, destacou Fernando Rosa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" height=\"768\" width=\"1024\" src=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg?w=1024\" alt=\"\" class=\"wp-image-8465\" srcset=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg 3264w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg?resize=300,225 300w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg?resize=768,576 768w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg?resize=1024,768 1024w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg?resize=1536,1152 1536w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/DSC02460.jpg?resize=2048,1536 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Al\u00e9m da troca de conhecimento e experi\u00eancias, os participantes poder\u00e3o adquirir gen\u00e9tica com condi\u00e7\u00f5es e descontos exclusivos. Ser\u00e3o ofertados s\u00eamen convencional e gen\u00e9tica sexada Sexcel de importantes touros da bateria leite da ABS. Entre os destaques na ra\u00e7a Guzer\u00e1, estar\u00e3o os touros Samurai, Paysandu, Campon\u00eas e Dia Santo, e&nbsp; na ra\u00e7a Sindi, os destaques ser\u00e3o os reprodutores Xeque, Obo\u00e9, Olho de Fogo e Magno.<\/p>\n\n\n\n<p>\u201cSer\u00e3o ofertas imperd\u00edveis para os produtores levarem essa gen\u00e9tica para suas propriedades, acelerando o avan\u00e7o da produ\u00e7\u00e3o leiteira. Diretamente na live, os interessados poder\u00e3o enviar mensagens para nossa equipe que estar\u00e1 a postos. O ambiente virtual permite alcan\u00e7ar um n\u00famero muito expressivo de produtores e temos certeza de que ser\u00e1 um sucesso\u201d, ressaltou Fernando Rosa.<\/p>\n\n\n\n<p>Para participar, acesse o perfil da ABS no Instagram: @abspecplan<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" height=\"850\" width=\"1024\" src=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg?w=1024\" alt=\"\" class=\"wp-image-8466\" srcset=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg 4164w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg?resize=300,249 300w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg?resize=768,637 768w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg?resize=1024,850 1024w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg?resize=1536,1275 1536w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_9165.jpg?resize=2048,1700 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"824\" src=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/WhatsApp-Image-2024-02-16-at-11.25.13.jpeg\" alt=\"\" class=\"wp-image-8467\" srcset=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/WhatsApp-Image-2024-02-16-at-11.25.13.jpeg 828w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/WhatsApp-Image-2024-02-16-at-11.25.13.jpeg?resize=150,150 150w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/WhatsApp-Image-2024-02-16-at-11.25.13.jpeg?resize=300,300 300w, https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/WhatsApp-Image-2024-02-16-at-11.25.13.jpeg?resize=768,764 768w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o on-line vai ofertar s\u00eamen convencional e s\u00eamen sexado de touros de elevado valor gen\u00e9tico; live ser\u00e1 transmitida no Instagram da ABS, na pr\u00f3xima ter\u00e7a-feira (20), \u00e0s 19h A busca constante por mais produtividade e rendimento exige que os produtores invistam cada vez mais em gen\u00e9tica de qualidade. Com uma bateria de touros l\u00edder de [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-8463","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva\" \/>\n<meta property=\"og:description\" content=\"A\u00e7\u00e3o on-line vai ofertar s\u00eamen convencional e s\u00eamen sexado de touros de elevado valor gen\u00e9tico; live ser\u00e1 transmitida no Instagram da ABS, na pr\u00f3xima ter\u00e7a-feira (20), \u00e0s 19h A busca constante por mais produtividade e rendimento exige que os produtores invistam cada vez mais em gen\u00e9tica de qualidade. Com uma bateria de touros l\u00edder de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T14:36:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?w=1024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/\",\"url\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/\",\"name\":\"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?w=1024\",\"datePublished\":\"2024-02-16T14:36:55+00:00\",\"dateModified\":\"2024-02-16T14:36:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#primaryimage\",\"url\":\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg\",\"contentUrl\":\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg\",\"width\":4626,\"height\":3840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-dev.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-dev.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-dev.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-dev.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-dev.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva","og_description":"A\u00e7\u00e3o on-line vai ofertar s\u00eamen convencional e s\u00eamen sexado de touros de elevado valor gen\u00e9tico; live ser\u00e1 transmitida no Instagram da ABS, na pr\u00f3xima ter\u00e7a-feira (20), \u00e0s 19h A busca constante por mais produtividade e rendimento exige que os produtores invistam cada vez mais em gen\u00e9tica de qualidade. Com uma bateria de touros l\u00edder de [&hellip;]","og_url":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/","og_site_name":"ABS Global Brasil","article_modified_time":"2024-02-16T14:36:56+00:00","og_image":[{"url":"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?w=1024","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/","url":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/","name":"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-dev.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#primaryimage"},"image":{"@id":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#primaryimage"},"thumbnailUrl":"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg?w=1024","datePublished":"2024-02-16T14:36:55+00:00","dateModified":"2024-02-16T14:36:56+00:00","breadcrumb":{"@id":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#primaryimage","url":"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg","contentUrl":"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/02\/IMG_5790.jpg","width":4626,"height":3840},{"@type":"BreadcrumbList","@id":"https:\/\/www-dev.absglobal.com\/br\/noticias\/1a-live-shop-produtores-de-leite-poderao-adquirir-genetica-guzera-e-sindi-em-promocao-exclusiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-dev.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-dev.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"1\u00aa Live Shop: produtores de leite poder\u00e3o adquirir gen\u00e9tica Guzer\u00e1 e Sindi em promo\u00e7\u00e3o exclusiva"}]},{"@type":"WebSite","@id":"https:\/\/www-dev.absglobal.com\/br\/#website","url":"https:\/\/www-dev.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-dev.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-dev.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-dev.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-dev.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-dev.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-dev.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-dev.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/8463"}],"collection":[{"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=8463"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=8463"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=8463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}