{"id":3257,"date":"2020-05-15T10:48:58","date_gmt":"2020-05-15T15:48:58","guid":{"rendered":"https:\/\/www-dev.absglobal.com\/co\/?post_type=abs_news_article&#038;p=3257"},"modified":"2020-06-10T13:53:49","modified_gmt":"2020-06-10T18:53:49","slug":"abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico","status":"publish","type":"abs_news_article","link":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/","title":{"rendered":"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Los productores de m\u00e1s de 31 pa\u00edses se han enterado de los resultados obtenidos despu\u00e9s de usar la gen\u00e9tica ABS, as\u00ed como del semen sexado Sexcel, Beef in Focus y la transferencia de embriones<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El tercer d\u00eda de ABS Experience present\u00f3 dos nuevas visitas a propiedades 100% ABS de gran relevancia para la cadena del leche de los Estados Unidos, y brind\u00f3 a los 250 productores de m\u00e1s de 31 pa\u00edses que participaron en el viaje t\u00e9cnico m\u00e1s oportunidades para conocer de cerca los resultados ofrecidos por la gen\u00e9tica y la tecnolog\u00eda ABS.<\/p>\n\n\n\n<p>Primero, los ganaderos estuvieron en Black Soil, una lecher\u00eda que alberga un reba\u00f1o de la raza Holstein, centrada en la eficiencia lograda mediante el uso de herramientas como la gen\u00f3mica y los \u00edndices de evaluaci\u00f3n de animales, que permiten el c\u00e1lculo detallado del uso de transferencia de embriones, as\u00ed como productos ABS como la gen\u00e9tica sexada Sexcel, Icon Sires y Beef in Focus.<\/p>\n\n\n\n<p>El sistema altamente planificado sorprendi\u00f3 a los productores que visitaron la lecher\u00eda. El gerente de producci\u00f3n de una lecher\u00eda en Argentina, Emilio Paris, destaca la gesti\u00f3n de las actividades diarias de la propiedad como uno de los aprendizajes clave.<\/p>\n\n\n\n<p>\u201cEsta es la primera vez que visito los Estados Unidos y estoy impresionado por la estructura y la rentabilidad. Para darle una idea, orde\u00f1amos 2700 vacas con 75 personas, y aqu\u00ed en la lecher\u00eda que visitamos hay 5,000 vacas y solo 30 personas. La fuerza laboral tiene una eficiencia mucho mayor. Tambi\u00e9n estoy feliz de compartir esta experiencia con personas de todo el mundo y particularmente de Am\u00e9rica Latina. Estoy muy agradecido con ABS\u201d, celebra.<\/p>\n\n\n\n<p>Otro visitante, Luis Carlos Gallego, que trabaja en una cooperativa lechera colombiana, tambi\u00e9n se sorprendi\u00f3 por la propiedad. \u201cDe todo lo que tuvimos la oportunidad de saber en la finca, llevo a casa lo que aprendimos sobre el componente gen\u00e9tico. Tengo la intenci\u00f3n de aplicar el conocimiento adquirido aqu\u00ed para definir estrategias asociadas con el semen sexado y la transferencia de embriones para mejorar nuestro sistema de producci\u00f3n, aumentando nuestra competitividad a nivel internacional\u201d, dice.<\/p>\n\n\n\n<p>Despu\u00e9s de esto, el grupo visit\u00f3 Roorda Dairy, una propiedad fundada hace m\u00e1s de 10 a\u00f1os, donde hay una operaci\u00f3n con 3800 vacas, orde\u00f1adas tres veces al d\u00eda. Marcada por un sistema de producci\u00f3n avanzado, la granja utiliza la tecnolog\u00eda Beef in Focus en un impresionante 80% de la manada, maximizando la rentabilidad.<\/p>\n\n\n\n<p>El especialista en servicios t\u00e9cnicos de ABS, Evan Schnad, enfatiza que la gen\u00e9tica de la compa\u00f1\u00eda tiene una presencia absoluta en la propiedad. \u201cHacemos aqu\u00ed todas las inseminaciones, traemos todo el servicio t\u00e9cnico, tenemos un plan gen\u00e9tico moderno y aplican un \u00edndice de equipo personalizado, adem\u00e1s de Beef in Focus y semen sexado, lo que permite obtener la cantidad correcta de hembras\u201d, enfatiza.<\/p>\n\n\n\n<p>Al igual que con todas las visitas de ABS Experience, los visitantes no se fueron sin sorprenderse por los resultados obtenidos por el equipo. Esto es lo que nos cuenta el productor brasile\u00f1o Ant\u00f4nio Tinoco Neto, que dirige Fazenda Artagro, en Patos de Minas, Minas Gerais.<\/p>\n\n\n\n<p>\u201cEstamos visitando granjas excepcionales, y ABS Experience es muy emocionante para nosotros. Sorprendentemente, a pesar de su tama\u00f1o, son muy funcionales, aprovechan al m\u00e1ximo el espacio de orde\u00f1o al estilo americano y aprovechan el nuevo concepto l\u00e1cteo de combinar la producci\u00f3n de carne y leche. Felicidades ABS, estoy muy satisfecho con la experiencia\u201d, dice.<\/p>\n\n\n\n<p>ABS Experience. En el transcurso de esta semana, 250 ganaderos de m\u00e1s de 31 pa\u00edses participan en un tour intensivo por lecher\u00edas, laboratorios y otros lugares que representan todo el potencial de la producci\u00f3n lechera de los Estados Unidos, conociendo de cerca la alta productividad lograda a trav\u00e9s de la gen\u00e9tica ABS. El viaje termina el jueves (19).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los productores de m\u00e1s de 31 pa\u00edses se han enterado de los resultados obtenidos despu\u00e9s de usar la gen\u00e9tica ABS, as\u00ed como del semen sexado Sexcel, Beef in Focus y la transferencia de embriones El tercer d\u00eda de ABS Experience present\u00f3 dos nuevas visitas a propiedades 100% ABS de gran relevancia para la cadena del [&hellip;]<\/p>\n","protected":false},"author":289,"featured_media":2816,"template":"","abs_news_category":[101],"abs_news_tag":[],"class_list":["post-3257","abs_news_article","type-abs_news_article","status-publish","has-post-thumbnail","hentry","abs_news_category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico - ABS Global Colombia<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico\" \/>\n<meta property=\"og:description\" content=\"Los productores de m\u00e1s de 31 pa\u00edses se han enterado de los resultados obtenidos despu\u00e9s de usar la gen\u00e9tica ABS, as\u00ed como del semen sexado Sexcel, Beef in Focus y la transferencia de embriones El tercer d\u00eda de ABS Experience present\u00f3 dos nuevas visitas a propiedades 100% ABS de gran relevancia para la cadena del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Colombia\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-10T18:53:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg?fit=1280%2C718\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/\",\"url\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/\",\"name\":\"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico - ABS Global Colombia\",\"isPartOf\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg\",\"datePublished\":\"2020-05-15T15:48:58+00:00\",\"dateModified\":\"2020-06-10T18:53:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#primaryimage\",\"url\":\"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg\",\"contentUrl\":\"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg\",\"width\":1280,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-dev.absglobal.com\/co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News Articles\",\"item\":\"https:\/\/www-dev.absglobal.com\/co\/articles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/#website\",\"url\":\"https:\/\/www-dev.absglobal.com\/co\/\",\"name\":\"ABS Global Colombia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-dev.absglobal.com\/co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/#organization\",\"name\":\"ABS Global Colombia\",\"url\":\"https:\/\/www-dev.absglobal.com\/co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Colombia\"},\"image\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/co\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico - ABS Global Colombia","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico","og_description":"Los productores de m\u00e1s de 31 pa\u00edses se han enterado de los resultados obtenidos despu\u00e9s de usar la gen\u00e9tica ABS, as\u00ed como del semen sexado Sexcel, Beef in Focus y la transferencia de embriones El tercer d\u00eda de ABS Experience present\u00f3 dos nuevas visitas a propiedades 100% ABS de gran relevancia para la cadena del [&hellip;]","og_url":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/","og_site_name":"ABS Global Colombia","article_modified_time":"2020-06-10T18:53:49+00:00","og_image":[{"width":1280,"height":718,"url":"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg?fit=1280%2C718","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/","url":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/","name":"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico - ABS Global Colombia","isPartOf":{"@id":"https:\/\/www-dev.absglobal.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#primaryimage"},"image":{"@id":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#primaryimage"},"thumbnailUrl":"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg","datePublished":"2020-05-15T15:48:58+00:00","dateModified":"2020-06-10T18:53:49+00:00","breadcrumb":{"@id":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#primaryimage","url":"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg","contentUrl":"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/sexta.jpg","width":1280,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/www-dev.absglobal.com\/co\/articles\/abs-experience-la-tecnologia-se-destaca-durante-las-visitas-en-el-tercer-dia-del-viaje-tecnico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-dev.absglobal.com\/co\/"},{"@type":"ListItem","position":2,"name":"News Articles","item":"https:\/\/www-dev.absglobal.com\/co\/articles\/"},{"@type":"ListItem","position":3,"name":"ABS Experience: la tecnolog\u00eda se destaca durante las visitas en el tercer d\u00eda del viaje t\u00e9cnico"}]},{"@type":"WebSite","@id":"https:\/\/www-dev.absglobal.com\/co\/#website","url":"https:\/\/www-dev.absglobal.com\/co\/","name":"ABS Global Colombia","description":"","publisher":{"@id":"https:\/\/www-dev.absglobal.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-dev.absglobal.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www-dev.absglobal.com\/co\/#organization","name":"ABS Global Colombia","url":"https:\/\/www-dev.absglobal.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www-dev.absglobal.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-dev.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Colombia"},"image":{"@id":"https:\/\/www-dev.absglobal.com\/co\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_article\/3257"}],"collection":[{"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/users\/289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/media\/2816"}],"wp:attachment":[{"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/media?parent=3257"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_category?post=3257"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_tag?post=3257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}