{"id":5843,"date":"2021-08-27T16:59:15","date_gmt":"2021-08-27T21:59:15","guid":{"rendered":"https:\/\/www-dev.absglobal.com\/uk\/?post_type=abs_client&#038;p=5843"},"modified":"2021-08-27T17:11:57","modified_gmt":"2021-08-27T22:11:57","slug":"tom-matthews","status":"publish","type":"abs_client","link":"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/","title":{"rendered":"Tom Matthews"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":301,"featured_media":0,"template":"","abs_industry":[],"abs_herd_type":[],"abs_client_tag":[],"class_list":["post-5843","abs_client","type-abs_client","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tom Matthews - ABS Global UK<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tom Matthews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global UK\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-27T22:11:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/\",\"url\":\"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/\",\"name\":\"Tom Matthews - ABS Global UK\",\"isPartOf\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/#website\"},\"datePublished\":\"2021-08-27T21:59:15+00:00\",\"dateModified\":\"2021-08-27T22:11:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-dev.absglobal.com\/uk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clients\",\"item\":\"https:\/\/www-dev.absglobal.com\/uk\/clients\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tom Matthews\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/#website\",\"url\":\"https:\/\/www-dev.absglobal.com\/uk\/\",\"name\":\"ABS Global UK\",\"description\":\"Profit From Genetic Progress\",\"publisher\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-dev.absglobal.com\/uk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/#organization\",\"name\":\"ABS Global UK\",\"url\":\"https:\/\/www-dev.absglobal.com\/uk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-dev.absglobal.com\/uk\/wp-content\/uploads\/sites\/14\/2020\/03\/cropped-genu-abs.png\",\"contentUrl\":\"https:\/\/www-dev.absglobal.com\/uk\/wp-content\/uploads\/sites\/14\/2020\/03\/cropped-genu-abs.png\",\"width\":2542,\"height\":1080,\"caption\":\"ABS Global UK\"},\"image\":{\"@id\":\"https:\/\/www-dev.absglobal.com\/uk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tom Matthews - ABS Global UK","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Tom Matthews","og_url":"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/","og_site_name":"ABS Global UK","article_modified_time":"2021-08-27T22:11:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/","url":"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/","name":"Tom Matthews - ABS Global UK","isPartOf":{"@id":"https:\/\/www-dev.absglobal.com\/uk\/#website"},"datePublished":"2021-08-27T21:59:15+00:00","dateModified":"2021-08-27T22:11:57+00:00","breadcrumb":{"@id":"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www-dev.absglobal.com\/uk\/clients\/tom-matthews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-dev.absglobal.com\/uk\/"},{"@type":"ListItem","position":2,"name":"Clients","item":"https:\/\/www-dev.absglobal.com\/uk\/clients\/"},{"@type":"ListItem","position":3,"name":"Tom Matthews"}]},{"@type":"WebSite","@id":"https:\/\/www-dev.absglobal.com\/uk\/#website","url":"https:\/\/www-dev.absglobal.com\/uk\/","name":"ABS Global UK","description":"Profit From Genetic Progress","publisher":{"@id":"https:\/\/www-dev.absglobal.com\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-dev.absglobal.com\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www-dev.absglobal.com\/uk\/#organization","name":"ABS Global UK","url":"https:\/\/www-dev.absglobal.com\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www-dev.absglobal.com\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/www-dev.absglobal.com\/uk\/wp-content\/uploads\/sites\/14\/2020\/03\/cropped-genu-abs.png","contentUrl":"https:\/\/www-dev.absglobal.com\/uk\/wp-content\/uploads\/sites\/14\/2020\/03\/cropped-genu-abs.png","width":2542,"height":1080,"caption":"ABS Global UK"},"image":{"@id":"https:\/\/www-dev.absglobal.com\/uk\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/abs_client\/5843"}],"collection":[{"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/abs_client"}],"about":[{"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/types\/abs_client"}],"author":[{"embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/users\/301"}],"wp:attachment":[{"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/media?parent=5843"}],"wp:term":[{"taxonomy":"abs_industry","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/abs_industry?post=5843"},{"taxonomy":"abs_herd_type","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/abs_herd_type?post=5843"},{"taxonomy":"abs_client_tag","embeddable":true,"href":"https:\/\/www-dev.absglobal.com\/uk\/wp-json\/wp\/v2\/abs_client_tag?post=5843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}